{"id":2402,"date":"2018-07-12T00:45:06","date_gmt":"2018-07-11T21:45:06","guid":{"rendered":"http:\/\/www.cts-chile.cl\/?p=2402"},"modified":"2018-07-12T00:45:06","modified_gmt":"2018-07-11T21:45:06","slug":"historia-de-la-ciencia-y-de-la-tecnologia-en-chile","status":"publish","type":"post","link":"https:\/\/cts-chile.cl\/weblog\/2018\/07\/12\/historia-de-la-ciencia-y-de-la-tecnologia-en-chile\/","title":{"rendered":"Historia de la Ciencia y de la Tecnolog\u00eda en Chile"},"content":{"rendered":"<p>\u00a0<\/p>\n<p><strong>\u00daLTIMO PLAZO DE ENVIO DE RES\u00daMENES: LUNES 20 de AGOSTO de 2018<\/strong><\/p>\n<h1 class=\"entry-title\"><a href=\"https:\/\/labhcts.org\/2018\/07\/11\/llamado-a-publicar-2018\/\">Invitaci\u00f3n a Publicar\u00a0<\/a><\/h1>\n<p>El <a href=\"https:\/\/labhcts.org\/\">Laboratorio de Historia de la Ciencia, Tecnolog\u00eda y Sociedad<\/a> invita a presentar res\u00famenes hasta el 15 de AGOSTO para la publicaci\u00f3n:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/labhcts.org\/2018\/07\/11\/llamado-a-publicar-2018\/\"><strong>Historia de la Ciencia y de la Tecnolog\u00eda en Chile<\/strong><\/a><\/p>\n<p style=\"text-align: center;\">Carlos Sanhueza\/Lorena Valderrama<\/p>\n<p style=\"text-align: center;\">(Editores generales)<\/p>\n<p>El Laboratorio de Historia de la Ciencia y la Tecnolog\u00eda convoca a investigadoras e investigadores a participar en la realizaci\u00f3n de un libro sobre historia de la ciencia y la tecnolog\u00eda en Chile, que contar\u00e1 con revisi\u00f3n de pares y ser\u00e1 publicado en 2020. Los aportes al libro se organizar\u00e1n de acuerdo a los cinco ejes de la convocatoria y su desarrollo incluir\u00e1 un taller de trabajo colectivo.<\/p>\n<p>La invitaci\u00f3n es a presentar propuestas de trabajos originales para cap\u00edtulos del libro en cualquiera de los cinco ejes. La originalidad de los manuscritos implica que no hayan sido publicados ni presentados en congresos. Cada autor\/a podr\u00e1 presentar como m\u00e1ximo una propuesta de cap\u00edtulo en que figure como autor\/a principal y una propuesta de cap\u00edtulo en que aparezca como co-autor\/a.<\/p>\n<p>Los cap\u00edtulos tendr\u00e1n una extensi\u00f3n de entre 8.000 y 9.000 palabras. La selecci\u00f3n de propuestas de cap\u00edtulos la har\u00e1 cada grupo de editores de eje tem\u00e1tico en base a los res\u00famenes recibidos. Esta edici\u00f3n es una empresa colaborativa, lo que significa que todos los trabajos seleccionados deben participar en un taller de trabajo colectivo para sintonizar y enriquecer los manuscritos. Previo al taller, los participantes deber\u00e1n enviar un avance de aproximadamente 4.000 palabras que servir\u00e1 para preparar la actividad conjunta. Los trabajos finales se entregar\u00e1n en julio 2019,\u00a0 ser\u00e1n sometidos a revisi\u00f3n de pares evaluadores y, finalmente, al proceso de edici\u00f3n y publicaci\u00f3n.<\/p>\n<h1 class=\"entry-title\"><\/h1>\n<p><strong><em>Fechas importantes<\/em><\/strong><\/p>\n<ul>\n<li><strong>Convocatoria abierta para presentar res\u00famenes (300 a 400 palabras):<\/strong>\u00a015 de Junio al 15 de Agosto de 2018.\u00a0ENVIAR A EDITORES\/AS DEL EJE RESPECTIVO.<\/li>\n<li><strong>Anuncio de res\u00famenes aceptados:<\/strong>\u00a014 de Septiembre de 2018.<\/li>\n<li><strong>Recepci\u00f3n de avances (4000 palabras):<\/strong>\u00a015 de Diciembre de 2018.<\/li>\n<li><strong>Taller de presentaci\u00f3n y discusi\u00f3n de cap\u00edtulos:<\/strong>\u00a07 y 8 de Enero de 2019 (Valpara\u00edso).<\/li>\n<\/ul>\n<p><strong>Recepci\u00f3n de cap\u00edtulos (8000 a 9000 palabras) para evaluaci\u00f3n de pares externos:<\/strong>\u00a030 de Julio de 2019.<\/p>\n<h1 class=\"entry-title\"><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00daLTIMO PLAZO DE ENVIO DE RES\u00daMENES: LUNES 20 de AGOSTO de 2018 Invitaci\u00f3n a Publicar\u00a0 El Laboratorio de Historia de la Ciencia, Tecnolog\u00eda y Sociedad invita a presentar res\u00famenes hasta el 15 de AGOSTO para la publicaci\u00f3n: Historia de la Ciencia y de la Tecnolog\u00eda en Chile Carlos Sanhueza\/Lorena Valderrama (Editores generales) El Laboratorio<\/p>\n","protected":false},"author":1,"featured_media":2403,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-2402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-convocatorias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1772,"url":"https:\/\/cts-chile.cl\/weblog\/2017\/01\/11\/laboratorio-de-historia-de-la-ciencia-tecnologia-y-sociedad-y-proximo-encuentro-esocite\/","url_meta":{"origin":2402,"position":0},"title":"Laboratorio de Historia de la Ciencia, Tecnolog\u00eda y Sociedad y Pr\u00f3ximo Encuentro ESOCITE","author":"admin","date":"Enero 11, 2017","format":false,"excerpt":"A fines de 2016, el Laboratorio de Historia de la Ciencia, Tecnolog\u00eda y Sociedad, dirigido por\u00a0Carlos Sanhueza y con la coordinaci\u00f3n de Gloria Baigorrotegui y Andr\u00e9s G\u00f3mez Seguel, organiz\u00f3 la visita\u00a0Pablo Kreimer, parte de la\u00a0Sociedad Latinoamericana en Estudios Sociales de la Ciencia y la Tecnolog\u00eda (ESOCITE), para hablar\u00a0del futuro congreso\u2026","rel":"","context":"En &quot;Convocatorias&quot;","block_context":{"text":"Convocatorias","link":"https:\/\/cts-chile.cl\/weblog\/category\/convocatorias\/"},"img":{"alt_text":"","src":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2017\/01\/IMG_0045-1024x768.jpg","width":320,"height":0,"srcset":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2017\/01\/IMG_0045-1024x768.jpg 1x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2017\/01\/IMG_0045-1024x768.jpg 1.5x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2017\/01\/IMG_0045-1024x768.jpg 2x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2017\/01\/IMG_0045-1024x768.jpg 3x"},"classes":[]},{"id":868,"url":"https:\/\/cts-chile.cl\/weblog\/2015\/10\/31\/extension-de-plazo-para-presentar-resumenes\/","url_meta":{"origin":2402,"position":1},"title":"Extensi\u00f3n de plazo para presentar res\u00famenes","author":"admin","date":"Octubre 31, 2015","format":"image","excerpt":"El Comit\u00e9 Organizador ha\u00a0extendido el plazo hasta el d\u00eda 15 de Noviembre, 2015. III Encuentro CTS-Chile \u201cCiudadan\u00eda, Colectivo, Conocimiento y Poder.Logros y Desaf\u00edos para los estudios de Ciencia, Tecnolog\u00eda y Sociedad\u201d Los modos de comprender la articulaci\u00f3n del poder y el conocimiento est\u00e1n abriendo m\u00faltiples vetas de reflexi\u00f3n, intervenci\u00f3n y\u2026","rel":"","context":"En &quot;Convocatorias&quot;","block_context":{"text":"Convocatorias","link":"https:\/\/cts-chile.cl\/weblog\/category\/convocatorias\/"},"img":{"alt_text":"Logo","src":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg","width":320,"height":0},"classes":[]},{"id":781,"url":"https:\/\/cts-chile.cl\/weblog\/2015\/09\/11\/iii-encuentro-cts-chile-valparaiso-chile\/","url_meta":{"origin":2402,"position":2},"title":"Llamado a presentar res\u00famenes, III Encuentro CTS-Chile, Valpara\u00edso, Chile","author":"admin","date":"Septiembre 11, 2015","format":"image","excerpt":"\"Ciudadan\u00eda, Colectivo, Conocimiento y Poder. Logros y Desaf\u00edos para los estudios de Ciencia, Tecnolog\u00eda y Sociedad\" Los modos de comprender la articulaci\u00f3n del poder y el conocimiento est\u00e1n abriendo m\u00faltiples vetas de reflexi\u00f3n, intervenci\u00f3n y cr\u00edtica. En nuestro tercer encuentro queremos ahondar en estos modos situ\u00e1ndonos en nuestra am\u00e9rica latina\u2026","rel":"","context":"En &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/cts-chile.cl\/weblog\/category\/events\/"},"img":{"alt_text":"logo","src":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg","width":320,"height":0,"srcset":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 1x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 1.5x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 2x"},"classes":[]},{"id":2406,"url":"https:\/\/cts-chile.cl\/weblog\/2018\/08\/01\/infraestructuras-temporalidades-y-espacialidades-creaciones-tensiones-y-continuidades\/","url_meta":{"origin":2402,"position":3},"title":"VI Encuentro de la red CTS-Chile 2019:\u00a0&#8220;Infraestructuras, Temporalidades y Espacialidades: creaciones, tensiones y continuidades&#8221;","author":"admin","date":"Agosto 1, 2018","format":false,"excerpt":"Osorno es puerta de entrada a una de las regiones m\u00e1s emblem\u00e1ticas: la Patagonia Chilena y el 2019 ser\u00e1 sede del VI Encuentro de Ciencia, Tecnolog\u00eda y Sociedad CTS-Chile. Para esta ocasi\u00f3n se establece una importante l\u00ednea de reflexi\u00f3n que propone una lectura de las Infraestructuras \u2013tanto materiales como inmateriales-\u2026","rel":"","context":"En &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/cts-chile.cl\/weblog\/category\/events\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2575,"url":"https:\/\/cts-chile.cl\/weblog\/2014\/10\/17\/el-valor-de-los-estudios-de-ciencia-y-tecnologia-en-chile\/","url_meta":{"origin":2402,"position":4},"title":"El valor de los estudios de ciencia y tecnolog\u00eda en Chile","author":"admin","date":"Octubre 17, 2014","format":"image","excerpt":"Por\u00a0Yuri Carvajal,\u00a0Profesor, M\u00e9dico y editor de la Revista Chilena de Salud P\u00fablica. Octubre 15, 2014. Publicado en:\u00a0Sentidos Comunes. Es dif\u00edcil explicar el valor de una aproximaci\u00f3n practicada con alegr\u00eda e intensidad en los \u00faltimos 5 a\u00f1os, por un investigador. Los argumentos se mezclan con los gustos, las afinidades electivas, el\u2026","rel":"","context":"En &quot;Columnas&quot;","block_context":{"text":"Columnas","link":"https:\/\/cts-chile.cl\/weblog\/category\/columnas\/"},"img":{"alt_text":"LABORATORIO","src":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg","width":320,"height":0,"srcset":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 1x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 1.5x"},"classes":[]},{"id":1673,"url":"https:\/\/cts-chile.cl\/weblog\/2016\/11\/05\/convocatoria-iv-encuentro-de-la-red-chilena-de-estudios-en-ciencia-tecnologia-y-sociedad-cartografias-liquidas-y-territorios-sociotecnicos\/","url_meta":{"origin":2402,"position":5},"title":"Convocatoria:  IV Encuentro de la Red Chilena de Estudios en Ciencia, Tecnolog\u00eda y Sociedad: Cartograf\u00edas L\u00edquidas y Territorios Sociot\u00e9cnicos","author":"admin","date":"Noviembre 5, 2016","format":false,"excerpt":"Ampliaci\u00f3n de per\u00edodo para recepci\u00f3n de res\u00famenes: 11 de diciembre de 2016. Puedes encontrar m\u00e1s informaci\u00f3n en el siguiente enlace.","rel":"","context":"En &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/cts-chile.cl\/weblog\/category\/events\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/posts\/2402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/comments?post=2402"}],"version-history":[{"count":0,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/posts\/2402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/media?parent=2402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/categories?post=2402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/tags?post=2402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}