{"id":107,"date":"2019-05-13T02:18:31","date_gmt":"2019-05-13T02:18:31","guid":{"rendered":"http:\/\/td_uid_23_5cd8d3f7cf27c"},"modified":"2024-10-11T01:08:57","modified_gmt":"2024-10-11T01:08:57","slug":"encuentrocts2020","status":"publish","type":"post","link":"https:\/\/cts-chile.cl\/weblog\/2019\/05\/13\/encuentrocts2020\/","title":{"rendered":"VII Encuentro Anual de la Red CTS-Chile, enero 2020"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Convocatoria<\/strong> <\/h3>\n\n\n\n<p style=\"text-align:right\"><em>Alteridad. Del lat\u00edn alteritas, literalmente \u201ccualidad de ser otro\u201d, o estado de ser radicalmente ajeno al yo consciente o a una orientaci\u00f3n cultural particular. Cualidad de no ser igual; ser distinto o diferente de lo que de otra manera se experimenta o conoce.<\/em><\/p>\n\n\n\n<p>Desastres ecol\u00f3gicos a escala planetaria. Fragmentaci\u00f3n socioterritorial por modelos de desarrollismo extractivista. Proliferaci\u00f3n de tecnolog\u00edas de vigilancia, normalizaci\u00f3n y control. El avance de las \u2018fake news\u2019 como modo de gobierno. Violencia sistem\u00e1tica contra pueblos originarios y comunidades locales. La instalaci\u00f3n e intersecci\u00f3n de varias formas de discriminaci\u00f3n por g\u00e9nero, raza y clase. Vivimos en tiempos catastr\u00f3ficos que nos interpelan como comunidad CTS. La pregunta crucial, como algunos y algunas han insistido, ya no es c\u00f3mo los estudios CTS pueden investigar estos fen\u00f3menos, sino hasta qu\u00e9 punto pueden y deben\u00a0<em>intervenir<\/em>en ellos.<\/p>\n\n\n\n<p>En el VII Encuentro 2020 de la Red CTS-Chile queremos abrir un debate amplio y diverso sobre las pol\u00edticas de la intervenci\u00f3n a las que nos convocan los tiempos que vivimos en Chile, la regi\u00f3n y el mundo. Y lo hacemos heredando el llamado que pensadores y pensadoras decoloniales en Am\u00e9rica Latina han elevado desde hace ya varias d\u00e9cadas: que una intervenci\u00f3n capaz de cultivar verdaderos espacios onto-epistemol\u00f3gicos de emancipaci\u00f3n debe hacerse desde, para y a trav\u00e9s de la\u00a0<em>alteridad<\/em>. Por alteridad entendemos otras formas de pensar, habitar y dise\u00f1ar; conocimientos equ\u00edvocos que proponen otras categor\u00edas de realidad; pr\u00e1cticas que desbordan los l\u00edmites impuestos por la tecnociencia; comunidades, humanas o no, que proponen sociabilidades ajenas al programa liberal.<\/p>\n\n\n\n<p>Nos interesa pensar la alteridad como un territorio f\u00e9rtil y convocante para los estudios CTS, tanto para denunciar y resistir m\u00faltiples violencias tecnocient\u00edficas, como para urdir espacios de esperanza y solidaridad. Tomamos la figura del\u00a0<em>cuidado<\/em>\u2013en tanto \u00e9tica ecol\u00f3gica sustentada en la interdependencia entre entidades divergentes\u2014para pensar c\u00f3mo las pr\u00e1cticas, teor\u00edas y metodolog\u00edas CTS pueden ayudar a imaginar otros futuros posibles, futuros m\u00e1s sustentables, democr\u00e1ticos y equitativos. Y otros modos de conocimiento m\u00e1s inter y trans-disciplinarios donde sensibilidades cr\u00edticas de las ciencias sociales germinen junto a las artes, el dise\u00f1o, las humanidades y el activismo.<\/p>\n\n\n\n<p>Invocamos las figuras de la alteridad y el cuidado en la perspectiva de la cat\u00e1strofe ecol\u00f3gica que nos toca vivir, y que nos obliga a replantearnos las condiciones de la \u201cvida\u201d en el planeta y la existencia de un \u00fanico repertorio de lo real y lo imaginable. M\u00e1s que trasfondo cient\u00edfico a ser aceptado y sufrido, nos interesa la crisis planetaria (o lo que se ha llamado el \u201cantropoceno\u201d) como categor\u00eda flotante que indica el entrecruzamiento de procesos heterog\u00e9neos y multi-escalares y nos invita a pensar otros futuros posibles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fechas importantes<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>8 de abril:\u00a0<\/strong>Apertura postulaci\u00f3n de paneles abiertos, paneles cerrados y talleres u otras actividades.<\/li><li><strong>21 de junio:\u00a0<\/strong>Cierre postulaci\u00f3n de paneles abiertos, paneles cerrados y talleres u otras actividades.<\/li><li><strong>17 de julio:\u00a0<\/strong>Notificaci\u00f3n a organizadoras\/es de aceptaci\u00f3n paneles y talleres.<\/li><li><strong>22 de julio:\u00a0<\/strong>Apertura postulaci\u00f3n de res\u00famenes.<\/li><li><strong>21 de octubre:\u00a0Cierre postulaci\u00f3n de res\u00famenes.<\/strong><\/li><li><strong>1 noviembre:\u00a0<\/strong>Notificaci\u00f3n de aceptaci\u00f3n res\u00famenes.<\/li><li><strong>15-17 enero 2020:\u00a0<\/strong>Encuentro CTS2020, Santiago de Chile.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Env\u00edo de res\u00famenes<\/strong><\/h3>\n\n\n\n<p>Usted puede participar en el encuentro a trav\u00e9s del env\u00edo de un resumen de ponencia o presentaci\u00f3n individual o grupal. Cada ponencia ser\u00e1 incluida en un Panel del Encuentro y tendr\u00e1 de 10 a 15 minutos para exponer su trabajo y recibir preguntas. El encuentro anual de la Red CTS-Chile tiene una particular vocaci\u00f3n por alentar a propuestas acad\u00e9micas que consideren la incorporaci\u00f3n de reflexiones sobre el campo de los estudios en Ciencia, Tecnolog\u00eda y Sociedad (CTS) as\u00ed como corrientes de pensamiento cercanas, sobretodo vinculados a enfoques y disciplinas que adopten perspectivas inter, trans y multidisciplinarias.<\/p>\n\n\n\n<p>Por favor, considere que su resumen debe contar con la siguiente informaci\u00f3n:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>T\u00edtulo de ponencia<\/li><li>Autor\/a\/es\/as (nombre y apellido)<\/li><li>Filiaci\u00f3n Institucional (si corresponde)<\/li><li>Resumen de ponencia (extensi\u00f3n m\u00e1xima de 250 palabras)<\/li><li>Resumen acotado de ponencia (50 palabras)<\/li><li>Seleccionar Panel a la que postula (el detalle de los paneles lo puede encontrar\u00a0<a href=\"https:\/\/ctschile2020.wordpress.com\/paneles\/\">aqu\u00ed<\/a>)<\/li><\/ol>\n\n\n\n<p>Con respecto a la\u00a0<strong>Selecci\u00f3n de Paneles<\/strong>. Le aconsejamos que pueda seleccionar uno de los 20 paneles acad\u00e9micos con los que este a\u00f1o cuenta el VII Encuentro Anual de CTS-Chile.\u00a0Este m\u00e9todo de organizaci\u00f3n de paneles permite estimular la formaci\u00f3n de nuevas redes de colaboraciones en torno a temas de inter\u00e9s para la comunidad cient\u00edfica y acad\u00e9mica tanto en Chile como en el extranjero. Los paneles abiertos han sido propuestos por acad\u00e9micos nacionales e internacionales, que trabajan en diferentes pa\u00edses, regiones, universidades, centros de investigaci\u00f3n, y se relacionan con casi todos los temas principales de CTS, a nivel local y global.<\/p>\n\n\n\n<p><em>* Los res\u00famenes recibidos que sean aceptados y que no est\u00e9n asociados con paneles abiertos ser\u00e1n organizados en paneles por el comit\u00e9 del programa.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ingreso de Resumen<\/strong><\/h3>\n\n\n\n<p>Para ingresar al formulario de postulaci\u00f3n seleccione el siguiente\u00a0<a href=\"https:\/\/forms.gle\/JWd1TyRGwYbAEdX69\">LINK<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Consultas<\/strong><\/h3>\n\n\n\n<p>Para cualquier duda o consulta comunicarse al Comit\u00e9 Organizador a\u00a0<a href=\"mailto:ctschile2020@gmail.com\">ctschile2020@gmail.com<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Web del Encuentro<\/h3>\n\n\n\n<p><a href=\"https:\/\/ctschile2020.wordpress.com\">https:\/\/ctschile2020.wordpress.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convocatoria Alteridad. Del lat\u00edn alteritas, literalmente \u201ccualidad de ser otro\u201d, o estado de ser radicalmente ajeno al yo consciente o a una orientaci\u00f3n cultural particular. Cualidad de no ser igual; ser distinto o diferente de lo que de otra manera se experimenta o conoce. Desastres ecol\u00f3gicos a escala planetaria. Fragmentaci\u00f3n socioterritorial por modelos de desarrollismo<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[86],"tags":[85,34],"class_list":["post-107","post","type-post","status-publish","format-standard","hentry","category-encuentros","tag-85","tag-encuentro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2628,"url":"https:\/\/cts-chile.cl\/weblog\/2019\/10\/07\/vii-encuentro-red-cts-chile-scl-2020\/","url_meta":{"origin":107,"position":0},"title":"VII Encuentro Red CTS-Chile, SCL 2020","author":"admin","date":"Octubre 7, 2019","format":false,"excerpt":"","rel":"","context":"En &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/cts-chile.cl\/weblog\/category\/events\/"},"img":{"alt_text":"","src":"https:\/\/www.cts-chile.cl\/wp-content\/uploads\/2019\/10\/02-623x1024.jpg","width":320,"height":0,"srcset":"https:\/\/www.cts-chile.cl\/wp-content\/uploads\/2019\/10\/02-623x1024.jpg 1x, https:\/\/www.cts-chile.cl\/wp-content\/uploads\/2019\/10\/02-623x1024.jpg 1.5x"},"classes":[]},{"id":1639,"url":"https:\/\/cts-chile.cl\/weblog\/2016\/10\/11\/1639-2\/","url_meta":{"origin":107,"position":1},"title":"Volc\u00e1n, Energ\u00eda y Comunidad","author":"admin","date":"Octubre 11, 2016","format":false,"excerpt":"Compartimos la invitaci\u00f3n al\u00a0Encuentro \"Volc\u00e1n, energ\u00eda y comunidad\", actividad que estamos organizando entre cuatro centros de investigaci\u00f3n (CEGA, NUMIES; CEDEL; CIIR) en Villarrica, Regi\u00f3n de la Araucan\u00eda, el pr\u00f3ximo 3 de noviembre de 2016. Los volcanes como referentes culturales, como fuente de recursos y como \u00edconos de la Regi\u00f3n ser\u00e1n\u2026","rel":"","context":"En &quot;Convocatorias&quot;","block_context":{"text":"Convocatorias","link":"https:\/\/cts-chile.cl\/weblog\/category\/convocatorias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2638,"url":"https:\/\/cts-chile.cl\/weblog\/2019\/10\/10\/se-amplia-plazo-para-envio-de-ponencias-vii-encuentro-cts-chile-2020\/","url_meta":{"origin":107,"position":2},"title":"VII Encuentro CTS-Chile 2020","author":"admin","date":"Octubre 10, 2019","format":false,"excerpt":"\u00a1Se amplia el plazo para env\u00edo de res\u00famenes hasta el d\u00eda 21 de Octubre. Te invitamos a enviar tu ponencia a alguno de los 20 paneles abiertos que tiene el VII Encuentro Anual de la Red CTS-Chile: Desaf\u00edos jur\u00eddico-pol\u00edticos en tecnolog\u00eda y entornos digitales, Pol\u00edticas de ciencia, tecnolog\u00eda e innovaci\u00f3n,\u2026","rel":"","context":"En &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/cts-chile.cl\/weblog\/category\/events\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2587,"url":"https:\/\/cts-chile.cl\/weblog\/2019\/01\/09\/vi-encuentro-cts-chile-osorno-2019\/","url_meta":{"origin":107,"position":3},"title":"VI Encuentro CTS-Chile Osorno 2019","author":"admin","date":"Enero 9, 2019","format":false,"excerpt":"Estimada comunidad\u00a0ceteciana Ya van quedando pocos d\u00edas para nuestro pr\u00f3ximo encuentro anual 2019, a realizarse en la Universidad Tecnol\u00f3gica de Chile INACAP Osorno, los d\u00edas 16, 17 y 18 de Enero. Les recordamos que las actividades comienzan el d\u00eda mi\u00e9rcoles 16 a las 8:30 con las inscripciones al encuentro, esto\u2026","rel":"","context":"En &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/cts-chile.cl\/weblog\/category\/events\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84,"url":"https:\/\/cts-chile.cl\/weblog\/2014\/10\/05\/pronta-a-abrirse-la-convocatoria-para-el-segundo-encuentro-cts-chile\/","url_meta":{"origin":107,"position":4},"title":"Pronta a abrirse la convocatoria para el Segundo Encuentro CTS-Chile","author":"admin","date":"Octubre 5, 2014","format":"image","excerpt":"Las universidades de la Frontera y Cat\u00f3lica de Temuco ser\u00e1n las sedes del Segundo Encuentro de la Red CTS-Chile. La fecha ser\u00e1 los d\u00edas 22 y 23 de Enero de 2015.","rel":"","context":"En &quot;Convocatorias&quot;","block_context":{"text":"Convocatorias","link":"https:\/\/cts-chile.cl\/weblog\/category\/convocatorias\/"},"img":{"alt_text":"homeHeaderTitleImage_es_ES","src":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg","width":320,"height":0},"classes":[]},{"id":982,"url":"https:\/\/cts-chile.cl\/weblog\/2016\/01\/04\/informacion-relevante-iii-encuentro-cts-chile\/","url_meta":{"origin":107,"position":5},"title":"Informaci\u00f3n relevante III Encuentro CTS-Chile.","author":"admin","date":"Enero 4, 2016","format":"image","excerpt":"\u00a0Investigadores(as) de la comunidad CTS, Nos es un agrado c\u00f3mo Comit\u00e9 Organizador hacerles llegar la informaci\u00f3n respecto a las actividades del encuentro CTS Chile, Valpara\u00edso 2016. Organizado por la\u00a0Pontificia Universidad Cat\u00f3lica de Valpara\u00edso, con la colaboraci\u00f3n de las Universidad de Valpara\u00edso, Universidad de Santiago y Universidad de Chile.\u00a0 \u00bfD\u00f3nde y\u2026","rel":"","context":"En &quot;Convocatorias&quot;","block_context":{"text":"Convocatorias","link":"https:\/\/cts-chile.cl\/weblog\/category\/convocatorias\/"},"img":{"alt_text":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg","src":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg","width":320,"height":0,"srcset":"http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 1x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 1.5x, http:\/\/cts-chile.cl\/wp-content\/uploads\/2014\/09\/cropped-Photo-Jun-07-11-31-45-AM.jpg 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/posts\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":1,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/posts\/107\/revisions"}],"predecessor-version":[{"id":2713,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/posts\/107\/revisions\/2713"}],"wp:attachment":[{"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/media?parent=107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/categories?post=107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cts-chile.cl\/weblog\/wp-json\/wp\/v2\/tags?post=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}